{"id":32150,"date":"2018-03-01T11:38:08","date_gmt":"2018-03-01T11:38:08","guid":{"rendered":"http:\/\/www.comisionporlamemoria.org\/jovenesymemoria\/?page_id=32150"},"modified":"2026-04-08T13:43:38","modified_gmt":"2026-04-08T16:43:38","slug":"vol-2","status":"publish","type":"page","link":"https:\/\/www.comisionporlamemoria.org\/jovenesymemoria\/colecciones\/vol-2\/","title":{"rendered":"Vol.2 Historias no contadas"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; background_image=\u00bbhttps:\/\/www.comisionporlamemoria.org\/jovenesymemoria\/wp-content\/uploads\/sites\/21\/2019\/02\/modelos_02-1.jpg\u00bb background_position=\u00bbbottom_center\u00bb custom_padding=\u00bb115px|0px|120px|0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; inner_shadow=\u00bbon\u00bb fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb||0||false|false\u00bb top_divider_style=\u00bbslant2&#8243; top_divider_color=\u00bb#2ef2c4&#8243; top_divider_height=\u00bb54px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_header title=\u00bbvol 2 | historias no contadas\u00bb subhead=\u00bbCortos audiovisuales realizados por j\u00f3venes de escuelas y organizaciones sociales\u00bb header_scroll_down=\u00bbon\u00bb scroll_down_icon=\u00bb%%7%%\u00bb scroll_down_icon_color=\u00bbrgba(0,0,0,0.66)\u00bb scroll_down_icon_size=\u00bb40px\u00bb _builder_version=\u00bb4.16&#8243; title_font=\u00bb||||||||\u00bb title_text_color=\u00bb#7f1d02&#8243; subhead_font=\u00bbRoboto Mono|300|||||||\u00bb subhead_text_color=\u00bb#333333&#8243; background_color=\u00bb#ffffff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px|0px|1px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_padding=\u00bb27px|0px|0px|0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span style=\"color: #7f1d02;\"> <strong>PEL\u00cdCULAS<\/strong><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px|0px|0px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_padding=\u00bb25.265625px|0px|0px|0px\u00bb global_colors_info=\u00bb{}\u00bb column_structure=\u00bb2_3,1_3&#8243;][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span style=\"color: rgba(0, 0, 0, 0.66);\"><strong>LA SANGRE DERRAMADA NO SER\u00c1 NEGOCIADA <\/strong><\/span><\/p>\n<p><span style=\"color: #2ef2c4;\">EEMN\u00b0 204- Bol\u00edvar<\/span><br \/><span style=\"color: #2ef2c4;\"> A\u00f1o 2007- 25 minutos<\/span><\/p>\n<p class=\"cuerpopeli\" style=\"text-align: justify;\">Este trabajo aborda el recorrido pol\u00edtico de Rodolfo Ortega Pe\u00f1a, abogado de organizaciones sindicales y de presos pol\u00edticos, asesinado en 1974 por la Triple A luego de haber asumido como diputado nacional. En esta producci\u00f3n los alumnos de la EEMN\u00b0 204 se centran en la visita de Ortega Pe\u00f1a a la ciudad de Bol\u00edvar, en la que particip\u00f3 de una cena con amigos. Sobre esta reuni\u00f3n, la Direcci\u00f3n de Inteligencia de la Provincia de Buenos Aires confeccion\u00f3 un detallado informe y los chicos no dejan de preguntarse c\u00f3mo la polic\u00eda obtuvo esa informaci\u00f3n.<\/p>\n<p>[\/et_pb_text][et_pb_toggle title=\u00bbPara trabajar la peli\u00bb icon_color=\u00bb#2ef2c4&#8243; open_icon_color=\u00bb#2ef2c4&#8243; admin_label=\u00bbLa sangre derramada no ser\u00e1 negociada\u00bb _builder_version=\u00bb4.16&#8243; title_text_color=\u00bbrgba(0,0,0,0.66)\u00bb title_font=\u00bb||||||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">La Alianza Anticomunista Argentina \u2013Triple A- fundada poco despu\u00e9s del inicio del gobierno de Per\u00f3n en 1973, fue una organizaci\u00f3n clandestina de inspiraci\u00f3n fascista que actu\u00f3 intensamente en la represi\u00f3n y desarticulaci\u00f3n de agrupaciones pol\u00edticas y sindicales de izquierda. Antesala de lo que ser\u00eda la m\u00e1s cruda represi\u00f3n vivida en la argentina durante la \u00faltima dictadura militar, la Triple A -seg\u00fan registros de la CONADEP- entre 1973 y principios de 1976 fue responsable de m\u00e1s de 900 desapariciones y asesinatos. En enero de 2007 estos cr\u00edmenes fueron declarados delitos de lesa humanidad e imprescriptibles seg\u00fan las normas legales vigentes; se se\u00f1al\u00f3 que la asociaci\u00f3n estableci\u00f3 una pr\u00e1ctica generalizada que constituy\u00f3 una grave violaci\u00f3n a los derechos humanos, ya que fueron implementados y llevados a cabo desde el Estado y por sujetos que respond\u00edan a ese poder.<br \/> Proponemos trabajar con Watu: historia de un asesinato en los pasillos de la UNS, un documental que puede ser un disparador para pensar en la dictadura no como un momento aislado en nuestra historia sino como un proceso atravesado por continuidades y rupturas. La militancia de los j\u00f3venes y la intervenci\u00f3n de la UNS, la violaci\u00f3n a los DDHH, el plan sistem\u00e1tico de tortura y desaparici\u00f3n, las secuelas en el presente, son algunos de los temas que los chicos de Bah\u00eda Blanca analizan en su investigaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #2db2c6;\">Ejes sugeridos<\/span><\/p>\n<p style=\"text-align: justify;\">&#8211; El terrorismo de Estado. Secuestros, desaparici\u00f3n y tortura como mecanismos de represi\u00f3n y miedo.<br \/> &#8211; Los vuelos de la muerte y las tumbas NN.<br \/> &#8211; Los silencios y miedos como parte del proceso rememorativo.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #2db2c6;\">Libros<\/span><\/p>\n<p style=\"text-align: justify;\">&#8211; Felipe Celesia y Pablo Waisberg (2007) La ley y las armas. Biograf\u00eda de Rodolfo Ortega Pe\u00f1a, Aguilar, Buenos Aires.<br \/> &#8211;\u00a0<u><a href=\"http:\/\/historiapolitica.com\/datos\/biblioteca\/Chama.pdf\" target=\"_blank\" rel=\"noopener\">Mauricio Chama,\u00a0<em>Movilizaci\u00f3n y pol\u00edtizaci\u00f3n: abogados de Buenos Aires entre 1968 y 1973<\/em><\/a><\/u><br \/> &#8211; Mart\u00ednez, Tom\u00e1s Eloy (2004) La pasi\u00f3n seg\u00fan Trelew, Aguilar, Buenos Aires<br \/> &#8211; Ram\u00edrez, Ana Julia Las mediaciones locales de la protesta: el caso del Trelewazo (octubre de 1972)<br \/> &#8211;\u00a0<u><a href=\"https:\/\/www.comisionporlamemoria.org\/archivos\/educacion\/memoria-en-las-aulas\/dossier10.pdf\" target=\"_blank\" rel=\"noopener\"><em>Dossier Educaci\u00f3n y Memoria Radicalizaci\u00f3n Pol\u00edtica (1966-1973)<\/em><\/a><\/u><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #2db2c6;\">Pel\u00edculas sugeridas<\/span><\/p>\n<p>&#8211; JP Rawson, Cr\u00f3nica de una militancia, de Nahuel Machesich<br \/> &#8211; Prohibido dormir, de Paula Bassi<br \/> &#8211; Trelew, de Mariana Arruti &#8211; http:\/\/www.filmtrelew.com.ar\/<\/p>\n<p><span style=\"color: #2db2c6;\">Producciones del programa J\u00f3venes y Memoria\u00a0<\/span><\/p>\n<p>-Watu, \u00bfsab\u00e9s qui\u00e9n fue?, Escuela Normal Superior, Bah\u00eda Blanca, 2007<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_video src=\u00bbhttps:\/\/www.youtube.com\/watch?v=8ePChph6W7M&#038;list=PL7IcFLoE4iLhBIyKtK6Bq4K9Yf-5AHEEv\u00bb _builder_version=\u00bb4.16&#8243; custom_margin=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_padding=\u00bb27px|0px|5px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px|0px|0px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_padding=\u00bb27px|0px|17px|0px\u00bb global_colors_info=\u00bb{}\u00bb column_structure=\u00bb2_3,1_3&#8243;][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span style=\"color: rgba(0, 0, 0, 0.66);\"> <strong>DESENTERRANDO SILENCIOS\u00a0<\/strong><\/span><\/p>\n<p><span style=\"color: #2ef2c4;\">Instituto Anchorena- Pergamino\u00a0<\/span><br \/><span style=\"color: #2ef2c4;\"> A\u00f1o 2007- 16 minutos<\/span><\/p>\n<p class=\"cuerpopeli\" style=\"text-align: justify;\">Una noticia en el semanario local lleva a los chicos a investigar sobre los NN en el cementerio. La aparici\u00f3n de un cuerpo calcinado en las inmediaciones de Pergamino, les permite indagar sobre el accionar de las fuerzas represivas en la zona, apelando al testimonio de un trabajador del cementerio local, que rompe un silencio de a\u00f1os.<\/p>\n<p>[\/et_pb_text][et_pb_toggle title=\u00bbPara trabajar la peli\u00bb icon_color=\u00bb#2ef2c4&#8243; open_icon_color=\u00bb#2ef2c4&#8243; admin_label=\u00bbDesenterrando silencios\u00bb _builder_version=\u00bb4.16&#8243; title_text_color=\u00bbrgba(0,0,0,0.66)\u00bb title_font=\u00bb||||||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">El secuestro y la desaparici\u00f3n de personas fue la principal metodolog\u00eda implementada por la dictadura militar para llevar adelante su plan de exterminio. Los centros clandestinos instalados en medio de las ciudades, la proliferaci\u00f3n de tumbas NN, la aparici\u00f3n de cuerpos con signos de tortura en playas y rutas, eran parte de una cotidianeidad atroz.<br \/> Proponemos el caso que cuentan los chicos de Pergamino, \u2013un cad\u00e1ver con claras marcas de tortura, es encontrado en la vera de la ruta y enterrado en silencio por el sepulturero\u2013, para indagar en los mecanismos de violencia efectuados por la dictadura, en donde la visualizaci\u00f3n de los cuerpos y la tortura formaron en parte de la maquinaria del terror. Los alumnos realizan un gran trabajo de investigaci\u00f3n en donde se encuentran con los libros de entrada del cementerio en los que faltan hojas, y con los testimonios de quienes se encontraron con el horror.<br \/> Tambi\u00e9n es interesante indagar en el testimonio del trabajador del cementerio y del periodista del diario para pensar en las \u201cotras memorias\u201d, la de quienes no suelen ser escuchados.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #2db2c6;\">Ejes sugeridos<\/span><\/p>\n<p style=\"text-align: justify;\">&#8211; Control y reordenamiento del espacio. Plan de erradicaci\u00f3n de villas.<br \/> &#8211; Organizaci\u00f3n vecinal y resistencias.<br \/> &#8211; Pobreza y exclusi\u00f3n. La estigmatizaci\u00f3n y discriminaci\u00f3n de la poblaci\u00f3n villera como parte de la propaganda ideol\u00f3gica de la dictadura.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #2db2c6;\">Otros recursos<\/span><\/p>\n<p style=\"text-align: justify;\"><u><a href=\"https:\/\/www.comisionporlamemoria.org\/archivos\/educacion\/educacion-y-memoria\/5.pdf\" target=\"_blank\" rel=\"noopener\">Dossier Educaci\u00f3n y memoria. Las grietas de la impunidad. 1990- 2001<\/a><\/u><br \/> <u><\/u><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #2db2c6;\">Libros y art\u00edculos<\/span><\/p>\n<p style=\"text-align: justify;\"><u><a href=\"http:\/\/www.pparg.org\/pparg\/documentos\/represion\/analisis_desaparicion\/_b\/contentFiles\/El_Estado_terrorista_Argentino_-_Duhalde.pdf\" target=\"_blank\" rel=\"noopener\">Duhalde Eduardo, El Estado terrorista<\/a><\/u><br \/> . Horacio Verbitsky (2007) El vuelo, Buenos Aires, Planeta, (1\u00ba edici\u00f3n 1995)<br \/> <u><a href=\"http:\/\/www.pparg.org\/pparg\/documentos\/represion\/analisis_desaparicion\/_b\/contentFiles\/Poder_y_Desaparicion_-_Calveiro.pdf\" target=\"_blank\" rel=\"noopener\">Calveiro, Pilar (2001) Poder y desaparici\u00f3n<\/a><\/u><\/p>\n<p><span style=\"color: #2db2c6;\">Producciones de J\u00f3venes y Memoria<\/span><\/p>\n<p>&#8211; NN: ni en el r\u00edo ni en las tumbas, EEMN\u00ba 2, Punta Indio, Ver\u00f3nica, 2006<br \/> &#8211; Alas de la memoria, EEMN\u00ba 2 de Ituzaingo, 2008.<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_video src=\u00bbhttps:\/\/www.youtube.com\/watch?v=qgVT33Hgx3w&#038;list=PL7IcFLoE4iLhBIyKtK6Bq4K9Yf-5AHEEv&#038;index=2&#8243; _builder_version=\u00bb4.16&#8243; custom_margin=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px|0px|0px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb column_structure=\u00bb2_3,1_3&#8243;][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span style=\"color: rgba(0, 0, 0, 0.66);\"> <strong>LA GENERACI\u00d3N DEL SILENCIO NOS CUENTA \u00bfTEMOR U OLVIDO?<\/strong><\/span><\/p>\n<p><span style=\"color: #2ef2c4;\">Colegio Termas Huinco- Mar del Plata<\/span><br \/><span style=\"color: #2ef2c4;\"> A\u00f1o 2008- 28 minutos<\/span><\/p>\n<p class=\"cuerpopeli\" style=\"text-align: justify;\">P<span class=\"cuerpopeli\">artiendo de la inquietud de una alumna sobre el destino de sus t\u00edos desaparecidos, los chicos comienzan a preguntar sobre las historias de personas del puerto de Mar del Plata desaparecidas durante la \u00faltima dictadura militar y la trama de silencio construida en relaci\u00f3n a sus vidas, sus luchas y sus sue\u00f1os. De esta manera, a partir de testimonios de familiares y vecinos, reconstruyen la militancia y desaparici\u00f3n de una joven pareja de apellido Sasso y entrecruzan esta historia con la conformaci\u00f3n de una Comisi\u00f3n de la Memoria Portuaria, la lucha sindical por el convenio colectivo de trabajo de los fileteros, las listas negras y las reivindicaciones a\u00fan pendientes de los trabajadores del puerto.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_toggle title=\u00bbPara trabajar la peli\u00bb icon_color=\u00bb#2ef2c4&#8243; open_icon_color=\u00bb#2ef2c4&#8243; admin_label=\u00bbLa generaci\u00f3n del silencio nos cuenta \u00bfTemor u Olvido?\u00bb _builder_version=\u00bb4.16&#8243; title_text_color=\u00bbrgba(0,0,0,0.66)\u00bb title_font=\u00bb||||||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">La brutal represi\u00f3n desatada sobre la sociedad entre 1976 y 1983, tuvo en los trabajadores su principal v\u00edctima. Las profundas transformaciones de la econom\u00eda que se implementaron para revertir la distribuci\u00f3n del ingreso requer\u00edan ser acompa\u00f1adas por un disciplinamiento de la mano de obra. Las cifras de la CONADEP estiman que el 30,2 % de los detenidos-desaparecidos eran trabajadores. El aniquilamiento y la represi\u00f3n sobre comisiones de delegados completas o un conjunto importante de los activistas sindicales en las plantas fabriles contaron no s\u00f3lo con la complicidad sino tambi\u00e9n con la participaci\u00f3n activa de las empresas. Sin embargo y a pesar de las intimidaciones, ocupaciones militares, los asesinatos, los encarcelamientos y la acci\u00f3n psicol\u00f3gica desplegada por los militares, los trabajadores continuaron expresando su descontento durante todo el per\u00edodo de la dictadura militar.<br \/> En este trabajo, los alumnos del Colegio Termas de Huinco, rescatan del silencio la desaparici\u00f3n de un trabajador del puerto y su esposa y nos proponen escuchar a los obreros portuarios, cuya voz, como la de tantos otros, no encontr\u00f3 un lugar en las memorias oficiales.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #2db2c6;\">Ejes sugeridos<\/span><\/p>\n<p style=\"text-align: justify;\">&#8211; Historias silenciadas. El testimonio como soporte para transmisi\u00f3n del pasado a las nuevas generaciones.<br \/> &#8211; Trabajo y dictadura: la censura, persecuci\u00f3n y represi\u00f3n a los trabajadores.<br \/> &#8211; Los objetivos y fundamentos de las entidades vinculadas a la construcci\u00f3n de la memoria en el presente.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #2db2c6;\">Otros recursos<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.comisionporlamemoria.org\/archivos\/educacion\/memoria-en-las-aulas\/dossier8.pdf\" target=\"_blank\" rel=\"noopener\">Dossier Educaci\u00f3n y Memoria. Sindicatos y trabajadores. 1973- 1983<\/a><br \/> <a href=\"http:\/\/ex.comisionporlamemoria.org\/investigacionyensenanza\/pdf_biblioteca\/Basualdo-%20Complicidad%20patronal-militar.pdf\" target=\"_blank\" rel=\"noopener\">Basualdo Victoria, Complicidad patronal-militar en la \u00faltima dictadura argentina y Los casos de Acindar, Astarsa, D\u00e1lmine Siderca, Ford, Ledesma y Mercedes Benz<\/a><br \/> <u><\/u><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #2db2c6;\">Libros y art\u00edculos<\/span><\/p>\n<p style=\"text-align: justify;\">&#8211; Lorenz Federico, (2007) Los zapatos de Carlito, Buenos Aires Editorial Norma<br \/> &#8211; Falcon, Ricardo, (1996) \u201cLa resistencia obrera a la dictadura militar\u201d, en Quiroga, Hugo y C\u00e9sar Tcach, eds., A veinte a\u00f1os del golpe. Con memoria democr\u00e1tica, Buenos Aires, Homo Sapiens Ediciones<br \/> &#8211; Pozzi, Pablo, (2008) La oposici\u00f3n obrera a la dictadura (1976-1982)<\/p>\n<p><span style=\"color: #2db2c6;\">Documentales de J\u00f3venes y Memoria\u00a0<\/span><\/p>\n<p>-Hilos de Julio, EEMN\u00ba 9, Lisandro Olmos, 2004<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_video src=\u00bbhttps:\/\/www.youtube.com\/watch?v=964KOK93NaY&#038;index=3&#038;list=PL7IcFLoE4iLhBIyKtK6Bq4K9Yf-5AHEEv\u00bb _builder_version=\u00bb4.16&#8243; custom_margin=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_padding=\u00bb27px|0px|6px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px|0px|0px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb column_structure=\u00bb2_3,1_3&#8243;][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span style=\"color: rgba(0, 0, 0, 0.66);\"> <b>LOS MUERTOS DE LA TAPERA DE PEREL<\/b><\/span><\/p>\n<p><span style=\"color: #2ef2c4;\">EEMN\u00ba 5- Mercedes<\/span><br \/><span style=\"color: #2ef2c4;\"> A\u00f1o 2008- 22 minutos<\/span><\/p>\n<p class=\"cuerpopeli\" style=\"text-align: justify;\">El 12 de julio de 1978, un comando del Ej\u00e9rcito al mando del jefe del Regimiento 6 de Mercedes, entr\u00f3 a una estancia en la zona rural y cuatro personas aparecieron muertas. Los medios de comunicaci\u00f3n de la \u00e9poca se refirieron a \u201cdelincuentes\u201d y a un \u201cenfrentamiento armado\u00bb, pero estas versiones no coinciden con los relatos que los vecinos les dieron a los chicos de la EEMN\u00ba 5.<\/p>\n<p>[\/et_pb_text][et_pb_toggle title=\u00bbPara trabajar la peli\u00bb icon_color=\u00bb#2ef2c4&#8243; open_icon_color=\u00bb#2ef2c4&#8243; admin_label=\u00bbLos muertos de la tapera de Perel\u00bb _builder_version=\u00bb4.16&#8243; title_text_color=\u00bbrgba(0,0,0,0.66)\u00bb title_font=\u00bb||||||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">Durante la \u00faltima dictadura militar las FFAA se encargaron de crear episodios que ocultaban los hechos represivos visti\u00e9ndolos de acciones de incumbencia policial, actos supuestamente delictivos que a trav\u00e9s de los medios de comunicaci\u00f3n eran publicados en la secci\u00f3n \u201cpoliciales\u201d, prohibiendo una posible investigaci\u00f3n por parte de los periodistas. De esta manera fue informada por los diarios de la localidad de Mercedes la historia de un aparente enfrentamiento de la FFAA con \u201cguerrilleros\u201d en una tapera que estaba en los campos de la zona de la familia Perel. \u201cDe ser un mito urbano, pas\u00f3 a ser un hecho hist\u00f3rico\u201d. Con esta frase, uno de los entrevistados resume esta historia. Las versiones, los relatos que circulan frente al hecho dan cuenta de una compleja trama en la construcci\u00f3n de la memoria colectiva.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #2db2c6;\">Ejes sugeridos<\/span><\/p>\n<p style=\"text-align: justify;\">&#8211; Las diferentes percepciones sobre pasado y las m\u00faltiples dimensiones en la reconstrucci\u00f3n de los hechos.<br \/> &#8211; Las formas de ocultamiento y simulaci\u00f3n de los actos represivos por parte de las FFAA<br \/> &#8211; La censura en los medios de comunicaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #2db2c6;\">Otros recursos<\/span><\/p>\n<p style=\"text-align: justify;\"><u><a href=\"https:\/\/laasociacion.files.wordpress.com\/2015\/11\/memoria-jelc3adn-1.pdf\" target=\"_blank\" rel=\"noopener\">Jelin Elizabeth, \u201cDe qu\u00e9 hablamos cuando hablamos de memoria\u201d<\/a><\/u><br \/> <a href=\"https:\/\/www.comisionporlamemoria.org\/archivos\/puentes\/01puentes.pdf\">Jelin Elizabeth, \u201cMemorias en conflicto\u201d, en Revista Puentes, N\u00ba 1, a\u00f1o 1<\/a><br \/> &#8211;\u00a0<u><a href=\"http:\/\/rayandolosconfines.com\/pc_schmucler.html\" target=\"_blank\" rel=\"noopener\">Schmucler, H\u00e9ctor, \u201cNi siquiera un rostro donde la muerte hubiera podido estampar su sello (reflexiones sobre los desaparecidos y la memoria)\u201d<\/a><\/u><br \/> <u><\/u><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #2db2c6;\">Art\u00edculos<\/span><\/p>\n<p>&#8211; Portelli, Alessandro, (2003) La orden ya fue ejecutada, Fondo de Cultura Econ\u00f3mica<u><\/u><\/p>\n<p><span style=\"color: #2db2c6;\">Pel\u00edculas sobre el tema<\/span><\/p>\n<p>-985, Instituto Adveniat, Mor\u00f3n, 2006<br \/> &#8211; Detr\u00e1s de las paredes (historias de aparecidos), EEMN\u00ba 3, San Nicol\u00e1s, 2008<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_video src=\u00bbhttps:\/\/www.youtube.com\/watch?v=3UADy10BwLg&#038;list=PL7IcFLoE4iLhBIyKtK6Bq4K9Yf-5AHEEv&#038;index=4&#8243; _builder_version=\u00bb4.16&#8243; custom_margin=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_padding=\u00bb27px|0px|12px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px|0px|0px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_padding=\u00bb20px|0px|18px|0px\u00bb global_colors_info=\u00bb{}\u00bb column_structure=\u00bb2_3,1_3&#8243;][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span style=\"color: rgba(0, 0, 0, 0.66);\"> <b>LO QUE SE DICE CON LO QUE SE CALLA<\/b><\/span><\/p>\n<p class=\"cuerpopeli\"><span style=\"color: #2ef2c4;\">Colegio San Mart\u00edn- Bah\u00eda Blanca\u00a0<\/span><br \/><span style=\"color: #2ef2c4;\"> A\u00f1o 2008- 20 minutos<\/span><\/p>\n<p>Este trabajo toma como punto de partida las publicaciones del diario La Nueva Provincia para rastrear y reconstruir a partir de sus p\u00e1ginas los conflictos que atravesaron a la empresa en el per\u00edodo previo a la dictadura. En julio de 1976, una nota titulada \u201cSon investigados dos homicidios\u201d hablaba sobre el hallazgo de los cad\u00e1veres de Heinrich y Loyola, dos obreros gr\u00e1ficos, dirigentes gremiales de La Nueva Provincia e integrantes del Sindicato de Artes Gr\u00e1ficas. Los chicos del Colegio San Mart\u00edn rescatan las voces de sus compa\u00f1eros y familiares para dar cuenta de la actividad sindical, la resistencia y el impacto del secuestro y asesinato de los dirigentes.<\/p>\n<p>[\/et_pb_text][et_pb_toggle title=\u00bbPara trabajar la peli\u00bb icon_color=\u00bb#2ef2c4&#8243; open_icon_color=\u00bb#2ef2c4&#8243; admin_label=\u00bbLo que se dice con lo que se calla\u00bb _builder_version=\u00bb4.16&#8243; title_text_color=\u00bbrgba(0,0,0,0.66)\u00bb title_font=\u00bb||||||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">El an\u00e1lisis sobre cu\u00e1l fue el rol que desempe\u00f1\u00f3 la prensa durante la \u00faltima dictadura militar se encuentra sujeto a las condiciones restrictivas de producci\u00f3n, circulaci\u00f3n y consumo de la informaci\u00f3n. En este marco, los medios gr\u00e1ficos tomaron diferentes posturas que fueron desde la oposici\u00f3n radical hasta la complicidad e incluso el apoyo ideol\u00f3gico. Pero no por eso fueron \u00f3rganos homog\u00e9neos que se vieron ajenos a conflictos internos. Este trabajo sobre el pol\u00e9mico diario bahiense, La Nueva Provincia, nos permite abordar los medios desde esta doble perspectiva.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #2db2c6;\">Ejes sugeridos<\/span><\/p>\n<p style=\"text-align: justify;\">&#8211; El rol de los medios de comunicaci\u00f3n durante la \u00faltima dictadura militar y en el presente. La libertad de expresi\u00f3n y la censura.<br \/> &#8211; Actividad sindical y resistencia de los trabajadores.<br \/> &#8211; Complicidad y colaboraci\u00f3n por parte de las c\u00fapulas de las empresas en el plan sistem\u00e1tico de represi\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #2db2c6;\">Otros recursos<\/span><\/p>\n<p style=\"text-align: justify;\"><u><a href=\"http:\/\/www.elortiba.org\/\" target=\"_blank\" rel=\"noopener\">C\u00f3mo oper\u00f3 la dictadura. Jornadas Cultura y Medios en Dictadura y Democracia<\/a><\/u><br \/> <u><\/u><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #2db2c6;\">Libros y art\u00edculos<\/span><\/p>\n<p style=\"text-align: justify;\">&#8211; Diaz, C\u00e9sar, La cuenta regresiva. La construcci\u00f3n period\u00edstica del golpe de Estado de 1976, La Cruj\u00eda, Buenos Aires, 2002.-<br \/> &#8211; Feld, Claudia, \u201cEl \u2018rating\u2019 de la memoria en la televisi\u00f3n argentina\u201d, en Richard, Nelly (Ed.), Pol\u00edticas y est\u00e9ticas de la memoria, Cuarto Propio, Santiago de Chile, 2000<br \/> &#8211;\u00a0<u><a href=\"http:\/\/www.riehr.com.ar\/archivos\/Investigacion\/Zapata.pdf\" target=\"_blank\" rel=\"noopener\">Zapata, Ana Bel\u00e9n,<em>\u00a0Pr\u00e1cticas de lucha y experiencia obrera en los gr\u00e1ficos del diario La Nueva Provincia<\/em>, 1973-1976<\/a><\/u><br \/> &#8211; Blaustein, Eduardo y Zubieta, Mart\u00edn (1998) Dec\u00edamos ayer. La prensa argentina bajo el proceso, Buenos Aires, Colihue<u><\/u><\/p>\n<p><span style=\"color: #2db2c6;\">Pel\u00edculas sobre el tema<\/span><\/p>\n<p>&#8211; Ford. Mucho m\u00e1s que un falcon verde, EEMN\u00ba 8. Gral Pacheco-Tigre. 2007<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_video src=\u00bbhttps:\/\/www.youtube.com\/watch?v=YZw0ZKmdVMY&#038;index=5&#038;list=PL7IcFLoE4iLhBIyKtK6Bq4K9Yf-5AHEEv\u00bb _builder_version=\u00bb4.16&#8243; custom_margin=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_padding=\u00bb27px|0px|0px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px|0px|0px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb column_structure=\u00bb1_2,1_2&#8243;][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; text_font=\u00bb|||on|||||\u00bb text_text_color=\u00bb#ffffff\u00bb background_color=\u00bbrgba(0,0,0,0.66)\u00bb custom_padding=\u00bb15px|15px|15px|15px\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<strong><span style=\"color: #ffffff;\">pod\u00e9s Solicitar las producciones del Programa J\u00f3venes y Memoria en: <a href=\"mailto:jovenes@comisionporlamemoria.org\">jovenes@comisionporlamemoria.org<\/a><\/span><\/strong>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PEL\u00cdCULASLA SANGRE DERRAMADA NO SER\u00c1 NEGOCIADA EEMN\u00b0 204- Bol\u00edvar A\u00f1o 2007- 25 minutos Este trabajo aborda el recorrido pol\u00edtico de Rodolfo Ortega Pe\u00f1a, abogado de organizaciones sindicales y de presos pol\u00edticos, asesinado en 1974 por la Triple A luego de haber asumido como diputado nacional. En esta producci\u00f3n los alumnos de la EEMN\u00b0 204 se [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":0,"parent":32140,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-32150","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/P8ryIF-8my","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.comisionporlamemoria.org\/jovenesymemoria\/wp-json\/wp\/v2\/pages\/32150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comisionporlamemoria.org\/jovenesymemoria\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.comisionporlamemoria.org\/jovenesymemoria\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.comisionporlamemoria.org\/jovenesymemoria\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comisionporlamemoria.org\/jovenesymemoria\/wp-json\/wp\/v2\/comments?post=32150"}],"version-history":[{"count":0,"href":"https:\/\/www.comisionporlamemoria.org\/jovenesymemoria\/wp-json\/wp\/v2\/pages\/32150\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.comisionporlamemoria.org\/jovenesymemoria\/wp-json\/wp\/v2\/pages\/32140"}],"wp:attachment":[{"href":"https:\/\/www.comisionporlamemoria.org\/jovenesymemoria\/wp-json\/wp\/v2\/media?parent=32150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}